{"id":2191,"date":"2025-04-24T13:48:12","date_gmt":"2025-04-24T17:48:12","guid":{"rendered":"https:\/\/www.vdh.virginia.gov\/norfolk\/?page_id=2191"},"modified":"2025-04-24T13:48:12","modified_gmt":"2025-04-24T17:48:12","slug":"rental-agreement","status":"publish","type":"page","link":"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/","title":{"rendered":"Rental Agreement for Cosmetology\/Massage Therapists\/Tattoo Artists"},"content":{"rendered":"<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_11' ><style>#gform_wrapper_11[data-form-index=\"0\"].gform-theme,[data-parent-form=\"11_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg width='640' height='640' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-img-choice-size: var(--gf-field-img-choice-size-md);--gf-field-img-choice-card-space: var(--gf-field-img-choice-card-space-md);--gf-field-img-choice-check-ind-size: var(--gf-field-img-choice-check-ind-size-md);--gf-field-img-choice-check-ind-icon-size: var(--gf-field-img-choice-check-ind-icon-size-md);--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style>\n                        <div class='gform_heading'>\n                            <p class='gform_description'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_11'  action='\/norfolk\/wp-json\/wp\/v2\/pages\/2191' data-formid='11' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_11' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_11_1\" class=\"gfield gfield--type-section gfield--input-type-section gsection field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\"><\/h3><div class='gsection_description' id='gfield_description_11_1'>This serves to notify the Norfolk Department of Public Health that the following renter has permission to operate out of my permitted establishment:<\/div><\/div><fieldset id=\"field_11_3\" class=\"gfield gfield--type-name gfield--input-type-name gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Renter&#039;s Information<\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name no_last_name no_suffix gf_name_has_1 ginput_container_name gform-grid-row' id='input_11_3'>\n                            \n                            <span id='input_11_3_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_3.3' id='input_11_3_3' value=''   aria-required='false'     \/>\n                                                    <label for='input_11_3_3' class='gform-field-label gform-field-label--type-sub '>Name of Renter<\/label>\n                                                <\/span>\n                            \n                            \n                            \n                        <\/div><\/fieldset><div id=\"field_11_4\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_4'>Phone<\/label><div class='ginput_container ginput_container_phone'><input name='input_4' id='input_11_4' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_11_5\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_5'>Occupation<\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_11_5' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_11_6\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_6'>DPOR or Board of Nursing Certification #<\/label><div class='ginput_container ginput_container_text'><input name='input_6' id='input_11_6' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><fieldset id=\"field_11_7\" class=\"gfield gfield--type-address gfield--input-type-address gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Address<\/legend>    \n                    <div class='ginput_complex ginput_container has_street has_street2 has_city has_state has_zip ginput_container_address gform-grid-row' id='input_11_7' >\n                         <span class='ginput_full address_line_1 ginput_address_line_1 gform-grid-col' id='input_11_7_1_container' >\n                                        <input type='text' name='input_7.1' id='input_11_7_1' value=''    aria-required='false'    \/>\n                                        <label for='input_11_7_1' id='input_11_7_1_label' class='gform-field-label gform-field-label--type-sub '>Street Address<\/label>\n                                    <\/span><span class='ginput_full address_line_2 ginput_address_line_2 gform-grid-col' id='input_11_7_2_container' >\n                                        <input type='text' name='input_7.2' id='input_11_7_2' value=''     aria-required='false'   \/>\n                                        <label for='input_11_7_2' id='input_11_7_2_label' class='gform-field-label gform-field-label--type-sub '>Address Line 2<\/label>\n                                    <\/span><span class='ginput_left address_city ginput_address_city gform-grid-col' id='input_11_7_3_container' >\n                                    <input type='text' name='input_7.3' id='input_11_7_3' value=''    aria-required='false'    \/>\n                                    <label for='input_11_7_3' id='input_11_7_3_label' class='gform-field-label gform-field-label--type-sub '>City<\/label>\n                                 <\/span><span class='ginput_right address_state ginput_address_state gform-grid-col' id='input_11_7_4_container' >\n                                        <input type='text' name='input_7.4' id='input_11_7_4' value=''      aria-required='false'    \/>\n                                        <label for='input_11_7_4' id='input_11_7_4_label' class='gform-field-label gform-field-label--type-sub '>State \/ Province \/ Region<\/label>\n                                      <\/span><span class='ginput_left address_zip ginput_address_zip gform-grid-col' id='input_11_7_5_container' >\n                                    <input type='text' name='input_7.5' id='input_11_7_5' value=''    aria-required='false'    \/>\n                                    <label for='input_11_7_5' id='input_11_7_5_label' class='gform-field-label gform-field-label--type-sub '>ZIP \/ Postal Code<\/label>\n                                <\/span><input type='hidden' class='gform_hidden' name='input_7.6' id='input_11_7_6' value='' \/>\n                    <div class='gf_clear gf_clear_complex'><\/div>\n                <\/div><\/fieldset><div id=\"field_11_9\" class=\"gfield gfield--type-date gfield--input-type-date gfield--input-type-datepicker gfield--datepicker-no-icon gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_9'>Date<\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_9' id='input_11_9' type='text' value='' class='datepicker gform-datepicker mdy datepicker_no_icon gdatepicker-no-icon'   placeholder='mm\/dd\/yyyy' aria-describedby=\"input_11_9_date_format\" aria-invalid=\"false\" \/>\n                            <span id='input_11_9_date_format' class='screen-reader-text'>MM slash DD slash YYYY<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_11_9' class='gform_hidden' value='https:\/\/www.vdh.virginia.gov\/content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/div><div id=\"field_11_10\" class=\"gfield gfield--type-section gfield--input-type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Permitted Establishment&#039;s Information<\/h3><\/div><div id=\"field_11_11\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_11'>Name of Establishment<\/label><div class='ginput_container ginput_container_text'><input name='input_11' id='input_11_11' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_11_12\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_12'>Phone<\/label><div class='ginput_container ginput_container_phone'><input name='input_12' id='input_11_12' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/div><fieldset id=\"field_11_13\" class=\"gfield gfield--type-address gfield--input-type-address gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Address<\/legend>    \n                    <div class='ginput_complex ginput_container has_street has_street2 has_city has_state has_zip ginput_container_address gform-grid-row' id='input_11_13' >\n                         <span class='ginput_full address_line_1 ginput_address_line_1 gform-grid-col' id='input_11_13_1_container' >\n                                        <input type='text' name='input_13.1' id='input_11_13_1' value=''    aria-required='false'    \/>\n                                        <label for='input_11_13_1' id='input_11_13_1_label' class='gform-field-label gform-field-label--type-sub '>Street Address<\/label>\n                                    <\/span><span class='ginput_full address_line_2 ginput_address_line_2 gform-grid-col' id='input_11_13_2_container' >\n                                        <input type='text' name='input_13.2' id='input_11_13_2' value=''     aria-required='false'   \/>\n                                        <label for='input_11_13_2' id='input_11_13_2_label' class='gform-field-label gform-field-label--type-sub '>Address Line 2<\/label>\n                                    <\/span><span class='ginput_left address_city ginput_address_city gform-grid-col' id='input_11_13_3_container' >\n                                    <input type='text' name='input_13.3' id='input_11_13_3' value=''    aria-required='false'    \/>\n                                    <label for='input_11_13_3' id='input_11_13_3_label' class='gform-field-label gform-field-label--type-sub '>City<\/label>\n                                 <\/span><span class='ginput_right address_state ginput_address_state gform-grid-col' id='input_11_13_4_container' >\n                                        <input type='text' name='input_13.4' id='input_11_13_4' value=''      aria-required='false'    \/>\n                                        <label for='input_11_13_4' id='input_11_13_4_label' class='gform-field-label gform-field-label--type-sub '>State \/ Province \/ Region<\/label>\n                                      <\/span><span class='ginput_left address_zip ginput_address_zip gform-grid-col' id='input_11_13_5_container' >\n                                    <input type='text' name='input_13.5' id='input_11_13_5' value=''    aria-required='false'    \/>\n                                    <label for='input_11_13_5' id='input_11_13_5_label' class='gform-field-label gform-field-label--type-sub '>ZIP \/ Postal Code<\/label>\n                                <\/span><input type='hidden' class='gform_hidden' name='input_13.6' id='input_11_13_6' value='' \/>\n                    <div class='gf_clear gf_clear_complex'><\/div>\n                <\/div><\/fieldset><div id=\"field_11_14\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_14'>DPOR Shop Certification #<\/label><div class='ginput_container ginput_container_text'><input name='input_14' id='input_11_14' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><fieldset id=\"field_11_15\" class=\"gfield gfield--type-name gfield--input-type-name gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Owner Name<\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name no_last_name no_suffix gf_name_has_1 ginput_container_name gform-grid-row' id='input_11_15'>\n                            \n                            <span id='input_11_15_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_15.3' id='input_11_15_3' value=''   aria-required='false'     \/>\n                                                    <label for='input_11_15_3' class='gform-field-label gform-field-label--type-sub '>Full Name<\/label>\n                                                <\/span>\n                            \n                            \n                            \n                        <\/div><\/fieldset><div id=\"field_11_16\" class=\"gfield gfield--type-date gfield--input-type-date gfield--input-type-datepicker gfield--datepicker-no-icon gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_16'>Date<\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_16' id='input_11_16' type='text' value='' class='datepicker gform-datepicker mdy datepicker_no_icon gdatepicker-no-icon'   placeholder='mm\/dd\/yyyy' aria-describedby=\"input_11_16_date_format\" aria-invalid=\"false\" \/>\n                            <span id='input_11_16_date_format' class='screen-reader-text'>MM slash DD slash YYYY<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_11_16' class='gform_hidden' value='https:\/\/www.vdh.virginia.gov\/content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_11' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_11' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_11' id='gform_theme_11' value='orbital' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_11' id='gform_style_settings_11' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_11' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='11' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='KlhmNjw0J3KrG\/g9eqkmnZhaGfotSKpJ0WMtjTIkSrq0QpftuKw2lMVmwnqmkOXOjYrWEENKkUGl1837yuJ5rFoNfeegiOzPqn07UGz5QIccpfE=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_11' value='WyJbXSIsImZkODQzZjIzM2EyNGQ0MzUzYjc2YzI3MzQ3OWI4OWM2Il0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_11' id='gform_target_page_number_11' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_11' id='gform_source_page_number_11' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 11, 'https:\/\/www.vdh.virginia.gov\/content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery('#gform_ajax_frame_11').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_11');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_11').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_11').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_11').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_11').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_11').val();gformInitSpinner( 11, 'https:\/\/www.vdh.virginia.gov\/content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery(document).trigger('gform_page_loaded', [11, current_page]);window['gf_submitting_11'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_11').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [11]);window['gf_submitting_11'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_11').text());}else{jQuery('#gform_11').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"11\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_11\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_11\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_11\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 11, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":670,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"tags":[],"class_list":["post-2191","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rental Agreement for Cosmetology\/Massage Therapists\/Tattoo Artists - Norfolk Health Department<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rental Agreement for Cosmetology\/Massage Therapists\/Tattoo Artists - Norfolk Health Department\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/\" \/>\n<meta property=\"og:site_name\" content=\"Norfolk Health Department\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/rental-agreement\\\/\",\"url\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/rental-agreement\\\/\",\"name\":\"Rental Agreement for Cosmetology\\\/Massage Therapists\\\/Tattoo Artists - Norfolk Health Department\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/#website\"},\"datePublished\":\"2025-04-24T17:48:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/rental-agreement\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/rental-agreement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/rental-agreement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rental Agreement for Cosmetology\\\/Massage Therapists\\\/Tattoo Artists\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/#website\",\"url\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/\",\"name\":\"Norfolk Health Department\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vdh.virginia.gov\\\/norfolk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rental Agreement for Cosmetology\/Massage Therapists\/Tattoo Artists - Norfolk Health Department","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/","og_locale":"en_US","og_type":"article","og_title":"Rental Agreement for Cosmetology\/Massage Therapists\/Tattoo Artists - Norfolk Health Department","og_url":"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/","og_site_name":"Norfolk Health Department","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/","url":"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/","name":"Rental Agreement for Cosmetology\/Massage Therapists\/Tattoo Artists - Norfolk Health Department","isPartOf":{"@id":"https:\/\/www.vdh.virginia.gov\/norfolk\/#website"},"datePublished":"2025-04-24T17:48:12+00:00","breadcrumb":{"@id":"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vdh.virginia.gov\/norfolk\/rental-agreement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vdh.virginia.gov\/norfolk\/"},{"@type":"ListItem","position":2,"name":"Rental Agreement for Cosmetology\/Massage Therapists\/Tattoo Artists"}]},{"@type":"WebSite","@id":"https:\/\/www.vdh.virginia.gov\/norfolk\/#website","url":"https:\/\/www.vdh.virginia.gov\/norfolk\/","name":"Norfolk Health Department","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vdh.virginia.gov\/norfolk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/pages\/2191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/users\/670"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/comments?post=2191"}],"version-history":[{"count":2,"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/pages\/2191\/revisions"}],"predecessor-version":[{"id":2193,"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/pages\/2191\/revisions\/2193"}],"wp:attachment":[{"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/media?parent=2191"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdh.virginia.gov\/norfolk\/wp-json\/wp\/v2\/tags?post=2191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}